{"id":6,"count":184,"description":"Veja as reportagens especias sobre ASSIS no EncontraAssis. Acompanhe informa\u00e7\u00f5es de tr\u00e2nsito, previs\u00e3o do tempo, agenda cultural e tudo que acontece na cidade.","link":"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/","name":"Not\u00edcias Assis","slug":"noticias-assis","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Not\u00edcias Assis - Encontra Assis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Not\u00edcias Assis - Encontra Assis\" \/>\n<meta property=\"og:description\" content=\"Veja as reportagens especias sobre ASSIS no EncontraAssis. Acompanhe informa\u00e7\u00f5es de tr\u00e2nsito, previs\u00e3o do tempo, agenda cultural e tudo que acontece na cidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Assis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/noticias-assis\\\/\",\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/noticias-assis\\\/\",\"name\":\"Arquivos Not\u00edcias Assis - Encontra Assis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/noticias-assis\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/noticias-assis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias Assis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/\",\"name\":\"Encontra Assis\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Assis e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Not\u00edcias Assis - Encontra Assis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Not\u00edcias Assis - Encontra Assis","og_description":"Veja as reportagens especias sobre ASSIS no EncontraAssis. Acompanhe informa\u00e7\u00f5es de tr\u00e2nsito, previs\u00e3o do tempo, agenda cultural e tudo que acontece na cidade.","og_url":"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/","og_site_name":"Encontra Assis","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/","url":"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/","name":"Arquivos Not\u00edcias Assis - Encontra Assis","isPartOf":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontraassis.com.br\/sobre\/noticias-assis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontraassis.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias Assis"}]},{"@type":"WebSite","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#website","url":"https:\/\/www.encontraassis.com.br\/sobre\/","name":"Encontra Assis","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Assis e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontraassis.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}