{"id":148,"date":"2012-03-13T09:28:00","date_gmt":"2012-03-13T11:28:00","guid":{"rendered":"http:\/\/www.encontraassis.com.br\/noticias\/?p=148"},"modified":"2019-04-29T18:25:40","modified_gmt":"2019-04-29T20:25:40","slug":"jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis","status":"publish","type":"post","link":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/","title":{"rendered":"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis"},"content":{"rendered":"<div class=\"079b4bb45e89223bc3d5efe1bba6f6a9\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A sa\u00fade p\u00fablica da cidade de Assis, no interior de S\u00e3o Paulo, est\u00e1 em alerta. Uma menor de 13 anos morreu v\u00edtima de febre maculosa. H\u00e1 oito anos a cidade n\u00e3o registrava casos da doen\u00e7a, que foi confirmada na \u00faltima quarta-feira (7) pelo Instituto Adolfo Lutz.<\/p>\n<p>A febre maculosa \u00e9 uma doen\u00e7a transmitida pelo carrapato-estrela. Para a Vigil\u00e2ncia Sanit\u00e1ria, a confirma\u00e7\u00e3o de febre maculosa deixa a cidade em estado de aten\u00e7\u00e3o. A adolescente estudava em uma escola e amigos da jovem disseram \u00e0 diretora que, dias antes da menor ser internada com sintomas da doen\u00e7a, ela esteva em um c\u00f3rrego onde teria nadado com o grupo de colegas. Para evitar novos casos, a dire\u00e7\u00e3o est\u00e1 orientando estudantes e pais.<\/p>\n<p>O c\u00f3rrego da Fortuna \u00e9 de f\u00e1cil acesso. A mata fechada atrai capivaras e outros animais hospedeiros do carrapato-estrela.<\/p>\n<p>A partir de agora, a Vigil\u00e2ncia Epidemiol\u00f3gica ir\u00e1 distribuir panfletos com orienta\u00e7\u00f5es sobre a doen\u00e7a. \u00c1reas de risco como o c\u00f3rrego ir\u00e3o receber placas para que os visitantes fiquem bem longe dos carrapatos.<\/p>\n<p><strong>Sintomas<\/strong><br \/>\nA pessoa infectada pode desenvolver sintomas de 2 a 14 dias ap\u00f3s a picada. Os sintomas podem praticamente n\u00e3o existir ou serem muito fracos, o que dificulta o diagn\u00f3stico.<\/p>\n<p>Nas pessoas que desenvolvem o quadro mais caracter\u00edstico, a febre pode ser moderada a alta, chegando at\u00e9 aos 40 graus. A febre pode durar de 2 a 3 semanas e, geralmente, a pessoa tem que restringir as suas atividades, sendo necess\u00e1rio repouso no leito. \u00c9 comum ter dor de cabe\u00e7a intensa, dor no corpo, calafrios e edema dos olhos e conjuntivas.<\/p>\n<p>Nos primeiros dias de febre pode aparecer a m\u00e1cula, de onde vem o nome da doen\u00e7a. S\u00e3o les\u00f5es de pele, r\u00f3seas, nos punhos e tornozelos, que progridem para o tronco e face. Em seguida atinge m\u00e3os e p\u00e9s. O local onde houve a picada pode formar uma \u00falcera necr\u00f3tica semelhante \u00e0 les\u00e3o de picada de aranha.<\/p>\n<p>A doen\u00e7a pode evoluir para cura espont\u00e2nea em 3 semanas. Por\u00e9m, nas formas mais graves, as les\u00f5es de pele s\u00e3o mais hemorr\u00e1gicas e podem ocorrer a necrose nos dedos, nas orelhas, no palato mole e nos genitais. Podem ser acompanhados de sangramento de gengivas, do nariz, v\u00f4mitos e tosse seca intensa. A mortalidade pode chegar at\u00e9 20% dos casos diagnosticados.<\/p>\n<p><em>Fonte: G1<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A sa\u00fade p\u00fablica da cidade de Assis, no interior de S\u00e3o Paulo, est\u00e1 em alerta. Uma menor de 13 anos morreu v\u00edtima de febre maculosa. H\u00e1 oito anos a cidade n\u00e3o registrava casos da doen\u00e7a, que foi confirmada na \u00faltima quarta-feira (7) pelo Instituto Adolfo Lutz. A febre maculosa \u00e9 uma doen\u00e7a transmitida pelo carrapato-estrela. Para a Vigil\u00e2ncia Sanit\u00e1ria, a confirma\u00e7\u00e3o de febre maculosa deixa a cidade em estado de aten\u00e7\u00e3o. A adolescente estudava em uma escola e amigos da jovem disseram \u00e0 diretora que, dias antes da menor ser internada com sintomas da doen\u00e7a, ela esteva em um c\u00f3rrego <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-148","post","type-post","status-publish","format-standard","hentry","category-servicos-assis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis - Encontra Assis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis - Encontra Assis\" \/>\n<meta property=\"og:description\" content=\"A sa\u00fade p\u00fablica da cidade de Assis, no interior de S\u00e3o Paulo, est\u00e1 em alerta. Uma menor de 13 anos morreu v\u00edtima de febre maculosa. H\u00e1 oito anos a cidade n\u00e3o registrava casos da doen\u00e7a, que foi confirmada na \u00faltima quarta-feira (7) pelo Instituto Adolfo Lutz. A febre maculosa \u00e9 uma doen\u00e7a transmitida pelo carrapato-estrela. Para a Vigil\u00e2ncia Sanit\u00e1ria, a confirma\u00e7\u00e3o de febre maculosa deixa a cidade em estado de aten\u00e7\u00e3o. A adolescente estudava em uma escola e amigos da jovem disseram \u00e0 diretora que, dias antes da menor ser internada com sintomas da doen\u00e7a, ela esteva em um c\u00f3rrego\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Assis\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-13T11:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-29T20:25:40+00:00\" \/>\n<meta name=\"author\" content=\"Encontra Assis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Assis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/\"},\"author\":{\"name\":\"Encontra Assis\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\"},\"headline\":\"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis\",\"datePublished\":\"2012-03-13T11:28:00+00:00\",\"dateModified\":\"2019-04-29T20:25:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/\"},\"wordCount\":421,\"commentCount\":0,\"articleSection\":[\"Servi\u00e7os Assis\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/\",\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/\",\"name\":\"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis - Encontra Assis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#website\"},\"datePublished\":\"2012-03-13T11:28:00+00:00\",\"dateModified\":\"2019-04-29T20:25:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/\",\"name\":\"Encontra Assis\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Assis e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\",\"name\":\"Encontra Assis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"caption\":\"Encontra Assis\"},\"sameAs\":[\"http:\\\/\\\/www.encontraassis.com.br\"],\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/author\\\/eassis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis - Encontra Assis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/","og_locale":"pt_BR","og_type":"article","og_title":"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis - Encontra Assis","og_description":"A sa\u00fade p\u00fablica da cidade de Assis, no interior de S\u00e3o Paulo, est\u00e1 em alerta. Uma menor de 13 anos morreu v\u00edtima de febre maculosa. H\u00e1 oito anos a cidade n\u00e3o registrava casos da doen\u00e7a, que foi confirmada na \u00faltima quarta-feira (7) pelo Instituto Adolfo Lutz. A febre maculosa \u00e9 uma doen\u00e7a transmitida pelo carrapato-estrela. Para a Vigil\u00e2ncia Sanit\u00e1ria, a confirma\u00e7\u00e3o de febre maculosa deixa a cidade em estado de aten\u00e7\u00e3o. A adolescente estudava em uma escola e amigos da jovem disseram \u00e0 diretora que, dias antes da menor ser internada com sintomas da doen\u00e7a, ela esteva em um c\u00f3rrego","og_url":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/","og_site_name":"Encontra Assis","article_published_time":"2012-03-13T11:28:00+00:00","article_modified_time":"2019-04-29T20:25:40+00:00","author":"Encontra Assis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Assis","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/#article","isPartOf":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/"},"author":{"name":"Encontra Assis","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff"},"headline":"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis","datePublished":"2012-03-13T11:28:00+00:00","dateModified":"2019-04-29T20:25:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/"},"wordCount":421,"commentCount":0,"articleSection":["Servi\u00e7os Assis"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/","url":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/","name":"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis - Encontra Assis","isPartOf":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/#website"},"datePublished":"2012-03-13T11:28:00+00:00","dateModified":"2019-04-29T20:25:40+00:00","author":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff"},"breadcrumb":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontraassis.com.br\/sobre\/jovem-de-13-anos-morre-vitima-da-febre-maculosa-em-assis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontraassis.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Jovem de 13 anos morre v\u00edtima da febre maculosa em Assis"}]},{"@type":"WebSite","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#website","url":"https:\/\/www.encontraassis.com.br\/sobre\/","name":"Encontra Assis","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Assis e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontraassis.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff","name":"Encontra Assis","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","caption":"Encontra Assis"},"sameAs":["http:\/\/www.encontraassis.com.br"],"url":"https:\/\/www.encontraassis.com.br\/sobre\/author\/eassis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":0,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}