{"id":306,"date":"2012-08-06T07:18:29","date_gmt":"2012-08-06T09:18:29","guid":{"rendered":"http:\/\/www.encontraassis.com.br\/noticias\/?p=306"},"modified":"2019-04-29T18:25:36","modified_gmt":"2019-04-29T20:25:36","slug":"estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo","status":"publish","type":"post","link":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/","title":{"rendered":"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo"},"content":{"rendered":"<div class=\"079b4bb45e89223bc3d5efe1bba6f6a9\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Estudantes da capital e do interior de S\u00e3o Paulo podem estagiar no Governo do Estado de S\u00e3o Paulo por meio do Programa de Est\u00e1gios da Funda\u00e7\u00e3o de Desenvolvimento Administrativo (Fundap). As inscri\u00e7\u00f5es para o processo seletivo do segundo semestre est\u00e3o abertas. Ser\u00e3o mais de 10 mil vagas disponibilizadas na capital e no interior de S\u00e3o Paulo, para atuar no Governo de S\u00e3o Paulo e na Assembleia Legislativa de S\u00e3o Paulo.<\/p>\n<p>At\u00e9 o dia 24 de agosto, podem se inscrever estudantes que estiverem regularmente matriculados em cursos de Ensino M\u00e9dio, Superior e educa\u00e7\u00e3o profissional de n\u00edvel m\u00e9dio (ou chamado t\u00e9cnico). Alunos com conclus\u00e3o da forma\u00e7\u00e3o prevista para dezembro de 2012 n\u00e3o poder\u00e3o concorrer \u00e0s vagas.<\/p>\n<p>As inscri\u00e7\u00f5es devem ser feitas no portal da Fundap, onde tamb\u00e9m os candidatos imprimem o boleto e efetuam o pagamento da taxa de inscri\u00e7\u00e3o, no valor de R$ 15,00, at\u00e9 o dia 27 de agosto. A prova ser\u00e1 realizada no dia 16 de setembro, \u00e0s 13h. A lista com as informa\u00e7\u00f5es sobre os respectivos locais de provas, data e hor\u00e1rio, ser\u00e1 divulgada a partir do dia 10 de setembro, no site da Fundap.<\/p>\n<p><strong>SERVI\u00c7O<\/strong><br \/>\n<strong>Programa de Est\u00e1gio do Governo do Estado de S\u00e3o Paulo<\/strong><br \/>\n<strong>Inscri\u00e7\u00f5es:<\/strong> at\u00e9 24 de agosto<br \/>\n<strong>Data limite\/pagamento inscri\u00e7\u00e3o:<\/strong> 27 de agosto<br \/>\n<strong>Divulga\u00e7\u00e3o da lista de inscritos:<\/strong> 30 de agosto<br \/>\n<strong>Divulga\u00e7\u00e3o local de prova:<\/strong> 10 de setembro<br \/>\n<strong>Prova:<\/strong> 16 de setembro<\/p>\n<p><em>Fonte: Portal do Governo do Estado<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Estudantes da capital e do interior de S\u00e3o Paulo podem estagiar no Governo do Estado de S\u00e3o Paulo por meio do Programa de Est\u00e1gios da Funda\u00e7\u00e3o de Desenvolvimento Administrativo (Fundap). As inscri\u00e7\u00f5es para o processo seletivo do segundo semestre est\u00e3o abertas. Ser\u00e3o mais de 10 mil vagas disponibilizadas na capital e no interior de S\u00e3o Paulo, para atuar no Governo de S\u00e3o Paulo e na Assembleia Legislativa de S\u00e3o Paulo. At\u00e9 o dia 24 de agosto, podem se inscrever estudantes que estiverem regularmente matriculados em cursos de Ensino M\u00e9dio, Superior e educa\u00e7\u00e3o profissional de n\u00edvel m\u00e9dio (ou chamado t\u00e9cnico). Alunos <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-306","post","type-post","status-publish","format-standard","hentry","category-empregos-assis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo - Encontra Assis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo - Encontra Assis\" \/>\n<meta property=\"og:description\" content=\"Estudantes da capital e do interior de S\u00e3o Paulo podem estagiar no Governo do Estado de S\u00e3o Paulo por meio do Programa de Est\u00e1gios da Funda\u00e7\u00e3o de Desenvolvimento Administrativo (Fundap). As inscri\u00e7\u00f5es para o processo seletivo do segundo semestre est\u00e3o abertas. Ser\u00e3o mais de 10 mil vagas disponibilizadas na capital e no interior de S\u00e3o Paulo, para atuar no Governo de S\u00e3o Paulo e na Assembleia Legislativa de S\u00e3o Paulo. At\u00e9 o dia 24 de agosto, podem se inscrever estudantes que estiverem regularmente matriculados em cursos de Ensino M\u00e9dio, Superior e educa\u00e7\u00e3o profissional de n\u00edvel m\u00e9dio (ou chamado t\u00e9cnico). Alunos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Assis\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-06T09:18:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-29T20:25:36+00:00\" \/>\n<meta name=\"author\" content=\"Encontra Assis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Assis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/\"},\"author\":{\"name\":\"Encontra Assis\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\"},\"headline\":\"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo\",\"datePublished\":\"2012-08-06T09:18:29+00:00\",\"dateModified\":\"2019-04-29T20:25:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/\"},\"wordCount\":267,\"commentCount\":0,\"articleSection\":[\"Empregos Assis\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/\",\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/\",\"name\":\"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo - Encontra Assis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#website\"},\"datePublished\":\"2012-08-06T09:18:29+00:00\",\"dateModified\":\"2019-04-29T20:25:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/\",\"name\":\"Encontra Assis\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Assis e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\",\"name\":\"Encontra Assis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"caption\":\"Encontra Assis\"},\"sameAs\":[\"http:\\\/\\\/www.encontraassis.com.br\"],\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/author\\\/eassis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo - Encontra Assis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/","og_locale":"pt_BR","og_type":"article","og_title":"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo - Encontra Assis","og_description":"Estudantes da capital e do interior de S\u00e3o Paulo podem estagiar no Governo do Estado de S\u00e3o Paulo por meio do Programa de Est\u00e1gios da Funda\u00e7\u00e3o de Desenvolvimento Administrativo (Fundap). As inscri\u00e7\u00f5es para o processo seletivo do segundo semestre est\u00e3o abertas. Ser\u00e3o mais de 10 mil vagas disponibilizadas na capital e no interior de S\u00e3o Paulo, para atuar no Governo de S\u00e3o Paulo e na Assembleia Legislativa de S\u00e3o Paulo. At\u00e9 o dia 24 de agosto, podem se inscrever estudantes que estiverem regularmente matriculados em cursos de Ensino M\u00e9dio, Superior e educa\u00e7\u00e3o profissional de n\u00edvel m\u00e9dio (ou chamado t\u00e9cnico). Alunos","og_url":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/","og_site_name":"Encontra Assis","article_published_time":"2012-08-06T09:18:29+00:00","article_modified_time":"2019-04-29T20:25:36+00:00","author":"Encontra Assis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Assis","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/#article","isPartOf":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/"},"author":{"name":"Encontra Assis","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff"},"headline":"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo","datePublished":"2012-08-06T09:18:29+00:00","dateModified":"2019-04-29T20:25:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/"},"wordCount":267,"commentCount":0,"articleSection":["Empregos Assis"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/","url":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/","name":"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo - Encontra Assis","isPartOf":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/#website"},"datePublished":"2012-08-06T09:18:29+00:00","dateModified":"2019-04-29T20:25:36+00:00","author":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff"},"breadcrumb":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontraassis.com.br\/sobre\/estudantes-de-assis-podem-estagiar-no-governo-do-estado-de-sao-paulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontraassis.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Estudantes de Assis podem estagiar no Governo do Estado de S\u00e3o Paulo"}]},{"@type":"WebSite","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#website","url":"https:\/\/www.encontraassis.com.br\/sobre\/","name":"Encontra Assis","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Assis e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontraassis.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff","name":"Encontra Assis","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","caption":"Encontra Assis"},"sameAs":["http:\/\/www.encontraassis.com.br"],"url":"https:\/\/www.encontraassis.com.br\/sobre\/author\/eassis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":0,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts\/306\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}