{"id":483,"date":"2013-04-18T00:20:12","date_gmt":"2013-04-18T02:20:12","guid":{"rendered":"http:\/\/www.encontraassis.com.br\/noticias\/?p=483"},"modified":"2019-04-29T18:24:58","modified_gmt":"2019-04-29T20:24:58","slug":"virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto","status":"publish","type":"post","link":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/","title":{"rendered":"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto"},"content":{"rendered":"<div class=\"079b4bb45e89223bc3d5efe1bba6f6a9\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A Secretaria da Cultura do Estado de S\u00e3o Paulo divulgou nesta semana a programa\u00e7\u00e3o parcial da 7\u00ba Virada Cultural Paulista, que ocorrer\u00e1 nos dias 25 e 26 de maio. Na regi\u00e3o, Assis, Bauru, Botucatu e Marilia (SP) est\u00e3o entre as 27 cidades do Estado que v\u00e3o receber os eventos gratuitos.<\/p>\n<p>Segundo o secret\u00e1rio de Cultura de Bauru, Elson Reis, neste ano haver\u00e1 uma atra\u00e7\u00e3o internacional na cidade, assim como nas demais participantes. A quantidade de bandas diminuiu, por\u00e9m, com o compromisso de artistas mais conhecidos.<\/p>\n<p>A programa\u00e7\u00e3o \u00a0contar\u00e1 com um palco externo no Paque Vit\u00f3ria R\u00e9gia que, com exce\u00e7\u00e3o do Stand Up de abertura, ser\u00e1 um palco exclusivo para atra\u00e7\u00f5es musicais. Entre um show e outro, um DJ realizar\u00e1 uma apresenta\u00e7\u00e3o no local, fazendo a conex\u00e3o entre o estilo musical de uma atra\u00e7\u00e3o para a pr\u00f3xima.<\/p>\n<p>As cidades que possuem teatro, como \u00e9 o caso da cidade de Bauru, contar\u00e3o com palco interno, com uma programa\u00e7\u00e3o de artes c\u00eanicas: teatro, dan\u00e7a, circo e cultura popular.<\/p>\n<p><strong>Confira informa\u00e7\u00f5es sobre o evento na cidade de Assis: <\/strong><\/p>\n<p><strong>S\u00c1BADO \u2013 25\/5<\/strong><br \/>\n19h &#8211; DJ Samuca Amaral<br \/>\n21h30 \u2013 Fabiana Cozza<br \/>\n23h \u2013 5 a Seco<br \/>\n0h30 &#8211; Otto<\/p>\n<p><strong>DOMINGO \u2013 26\/5<\/strong><br \/>\n15h30 \u2013 Nuno Mindelis<br \/>\n17h00 \u2013 Os Opalas<br \/>\n18h30 \u2013 Los Tres (Chile)<\/p>\n<p><em>Fonte: G1<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Secretaria da Cultura do Estado de S\u00e3o Paulo divulgou nesta semana a programa\u00e7\u00e3o parcial da 7\u00ba Virada Cultural Paulista, que ocorrer\u00e1 nos dias 25 e 26 de maio. Na regi\u00e3o, Assis, Bauru, Botucatu e Marilia (SP) est\u00e3o entre as 27 cidades do Estado que v\u00e3o receber os eventos gratuitos. Segundo o secret\u00e1rio de Cultura de Bauru, Elson Reis, neste ano haver\u00e1 uma atra\u00e7\u00e3o internacional na cidade, assim como nas demais participantes. A quantidade de bandas diminuiu, por\u00e9m, com o compromisso de artistas mais conhecidos. A programa\u00e7\u00e3o \u00a0contar\u00e1 com um palco externo no Paque Vit\u00f3ria R\u00e9gia que, com exce\u00e7\u00e3o do <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-483","post","type-post","status-publish","format-standard","hentry","category-noticias-assis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto - Encontra Assis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto - Encontra Assis\" \/>\n<meta property=\"og:description\" content=\"A Secretaria da Cultura do Estado de S\u00e3o Paulo divulgou nesta semana a programa\u00e7\u00e3o parcial da 7\u00ba Virada Cultural Paulista, que ocorrer\u00e1 nos dias 25 e 26 de maio. Na regi\u00e3o, Assis, Bauru, Botucatu e Marilia (SP) est\u00e3o entre as 27 cidades do Estado que v\u00e3o receber os eventos gratuitos. Segundo o secret\u00e1rio de Cultura de Bauru, Elson Reis, neste ano haver\u00e1 uma atra\u00e7\u00e3o internacional na cidade, assim como nas demais participantes. A quantidade de bandas diminuiu, por\u00e9m, com o compromisso de artistas mais conhecidos. A programa\u00e7\u00e3o \u00a0contar\u00e1 com um palco externo no Paque Vit\u00f3ria R\u00e9gia que, com exce\u00e7\u00e3o do\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Assis\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-18T02:20:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-29T20:24:58+00:00\" \/>\n<meta name=\"author\" content=\"Encontra Assis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Assis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/\"},\"author\":{\"name\":\"Encontra Assis\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\"},\"headline\":\"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto\",\"datePublished\":\"2013-04-18T02:20:12+00:00\",\"dateModified\":\"2019-04-29T20:24:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/\"},\"wordCount\":231,\"commentCount\":0,\"articleSection\":[\"Not\u00edcias Assis\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/\",\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/\",\"name\":\"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto - Encontra Assis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#website\"},\"datePublished\":\"2013-04-18T02:20:12+00:00\",\"dateModified\":\"2019-04-29T20:24:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/\",\"name\":\"Encontra Assis\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Assis e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/7e34afd5202806e3481cf2806e8f57ff\",\"name\":\"Encontra Assis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"caption\":\"Encontra Assis\"},\"sameAs\":[\"http:\\\/\\\/www.encontraassis.com.br\"],\"url\":\"https:\\\/\\\/www.encontraassis.com.br\\\/sobre\\\/author\\\/eassis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto - Encontra Assis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/","og_locale":"pt_BR","og_type":"article","og_title":"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto - Encontra Assis","og_description":"A Secretaria da Cultura do Estado de S\u00e3o Paulo divulgou nesta semana a programa\u00e7\u00e3o parcial da 7\u00ba Virada Cultural Paulista, que ocorrer\u00e1 nos dias 25 e 26 de maio. Na regi\u00e3o, Assis, Bauru, Botucatu e Marilia (SP) est\u00e3o entre as 27 cidades do Estado que v\u00e3o receber os eventos gratuitos. Segundo o secret\u00e1rio de Cultura de Bauru, Elson Reis, neste ano haver\u00e1 uma atra\u00e7\u00e3o internacional na cidade, assim como nas demais participantes. A quantidade de bandas diminuiu, por\u00e9m, com o compromisso de artistas mais conhecidos. A programa\u00e7\u00e3o \u00a0contar\u00e1 com um palco externo no Paque Vit\u00f3ria R\u00e9gia que, com exce\u00e7\u00e3o do","og_url":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/","og_site_name":"Encontra Assis","article_published_time":"2013-04-18T02:20:12+00:00","article_modified_time":"2019-04-29T20:24:58+00:00","author":"Encontra Assis","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Assis","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/#article","isPartOf":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/"},"author":{"name":"Encontra Assis","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff"},"headline":"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto","datePublished":"2013-04-18T02:20:12+00:00","dateModified":"2019-04-29T20:24:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/"},"wordCount":231,"commentCount":0,"articleSection":["Not\u00edcias Assis"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/","url":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/","name":"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto - Encontra Assis","isPartOf":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/#website"},"datePublished":"2013-04-18T02:20:12+00:00","dateModified":"2019-04-29T20:24:58+00:00","author":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff"},"breadcrumb":{"@id":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontraassis.com.br\/sobre\/virada-cultural-em-assis-tera-5-a-seco-em-botucatu-e-otto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontraassis.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Virada Cultural em Assis ter\u00e1 5 a Seco em Botucatu e Otto"}]},{"@type":"WebSite","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#website","url":"https:\/\/www.encontraassis.com.br\/sobre\/","name":"Encontra Assis","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Assis e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontraassis.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontraassis.com.br\/sobre\/#\/schema\/person\/7e34afd5202806e3481cf2806e8f57ff","name":"Encontra Assis","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","caption":"Encontra Assis"},"sameAs":["http:\/\/www.encontraassis.com.br"],"url":"https:\/\/www.encontraassis.com.br\/sobre\/author\/eassis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts\/483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=483"}],"version-history":[{"count":0,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/posts\/483\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontraassis.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}